{"id":62873,"date":"2026-07-13T15:30:55","date_gmt":"2026-07-13T20:30:55","guid":{"rendered":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/?post_type=dynamic-landing&#038;p=62873"},"modified":"2026-07-13T15:30:55","modified_gmt":"2026-07-13T20:30:55","slug":"hoteles-irotama","status":"publish","type":"dynamic-landing","link":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/hoteles-irotama\/","title":{"rendered":"Hoteles Irotama"},"featured_media":62887,"parent":0,"template":"","class_list":["post-62873","dynamic-landing","type-dynamic-landing","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hoteles Irotama - Tiquetes Baratos<\/title>\n<meta name=\"description\" content=\"Encuentra las mejores ofertas en hoteles Irotama. Reserva tu estancia en Santa Marta con descuentos exclusivos y vive una experiencia frente al Caribe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/hoteles-irotama\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hoteles Irotama - Tiquetes Baratos\" \/>\n<meta property=\"og:description\" content=\"Encuentra las mejores ofertas en hoteles Irotama. Reserva tu estancia en Santa Marta con descuentos exclusivos y vive una experiencia frente al Caribe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/hoteles-irotama\/\" \/>\n<meta property=\"og:site_name\" content=\"Tiquetes Baratos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PriceTravel\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/wp-content\/uploads\/2026\/07\/PH-Irotama-1920x470-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@PriceTravel\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tiquetesbaratos.com\\\/es\\\/ofertas-de-viajes\\\/hoteles-irotama\\\/\",\"url\":\"https:\\\/\\\/www.tiquetesbaratos.com\\\/es\\\/ofertas-de-viajes\\\/hoteles-irotama\\\/\",\"name\":\"Hoteles Irotama - Tiquetes Baratos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tiquetesbaratos.com\\\/es\\\/ofertas-de-viajes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tiquetesbaratos.com\\\/es\\\/ofertas-de-viajes\\\/hoteles-irotama\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tiquetesbaratos.com\\\/es\\\/ofertas-de-viajes\\\/hoteles-irotama\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tiquetesbaratos.com\\\/es\\\/ofertas-de-viajes\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/PH-Irotama-1920x470-2.jpg\",\"datePublished\":\"2026-07-13T20:30:55+00:00\",\"description\":\"Encuentra las mejores ofertas en hoteles Irotama. Reserva tu estancia en Santa Marta con descuentos exclusivos y vive una experiencia frente al Caribe.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tiquetesbaratos.com\\\/es\\\/ofertas-de-viajes\\\/hoteles-irotama\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tiquetesbaratos.com\\\/es\\\/ofertas-de-viajes\\\/hoteles-irotama\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.tiquetesbaratos.com\\\/es\\\/ofertas-de-viajes\\\/hoteles-irotama\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tiquetesbaratos.com\\\/es\\\/ofertas-de-viajes\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/PH-Irotama-1920x470-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tiquetesbaratos.com\\\/es\\\/ofertas-de-viajes\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/PH-Irotama-1920x470-2.jpg\",\"width\":1920,\"height\":470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tiquetesbaratos.com\\\/es\\\/ofertas-de-viajes\\\/hoteles-irotama\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tiquetesbaratos.com\\\/es\\\/ofertas-de-viajes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hoteles Irotama\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tiquetesbaratos.com\\\/es\\\/ofertas-de-viajes\\\/#website\",\"url\":\"https:\\\/\\\/www.tiquetesbaratos.com\\\/es\\\/ofertas-de-viajes\\\/\",\"name\":\"Tiquetes Baratos\",\"description\":\"M\u00e9xico, por ti viajar\u00e9\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tiquetesbaratos.com\\\/es\\\/ofertas-de-viajes\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tiquetesbaratos.com\\\/es\\\/ofertas-de-viajes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tiquetesbaratos.com\\\/es\\\/ofertas-de-viajes\\\/#organization\",\"name\":\"PriceTravel.com\",\"url\":\"https:\\\/\\\/www.tiquetesbaratos.com\\\/es\\\/ofertas-de-viajes\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.tiquetesbaratos.com\\\/es\\\/ofertas-de-viajes\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/3.12.161.119\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pricetravel.png\",\"contentUrl\":\"https:\\\/\\\/3.12.161.119\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pricetravel.png\",\"width\":422,\"height\":56,\"caption\":\"PriceTravel.com\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tiquetesbaratos.com\\\/es\\\/ofertas-de-viajes\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PriceTravel\",\"https:\\\/\\\/x.com\\\/PriceTravel\",\"https:\\\/\\\/www.instagram.com\\\/pricetravel\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hoteles Irotama - Tiquetes Baratos","description":"Encuentra las mejores ofertas en hoteles Irotama. Reserva tu estancia en Santa Marta con descuentos exclusivos y vive una experiencia frente al Caribe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/hoteles-irotama\/","og_locale":"en_US","og_type":"article","og_title":"Hoteles Irotama - Tiquetes Baratos","og_description":"Encuentra las mejores ofertas en hoteles Irotama. Reserva tu estancia en Santa Marta con descuentos exclusivos y vive una experiencia frente al Caribe.","og_url":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/hoteles-irotama\/","og_site_name":"Tiquetes Baratos","article_publisher":"https:\/\/www.facebook.com\/PriceTravel","og_image":[{"width":1920,"height":470,"url":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/wp-content\/uploads\/2026\/07\/PH-Irotama-1920x470-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@PriceTravel","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/hoteles-irotama\/","url":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/hoteles-irotama\/","name":"Hoteles Irotama - Tiquetes Baratos","isPartOf":{"@id":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/hoteles-irotama\/#primaryimage"},"image":{"@id":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/hoteles-irotama\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/wp-content\/uploads\/2026\/07\/PH-Irotama-1920x470-2.jpg","datePublished":"2026-07-13T20:30:55+00:00","description":"Encuentra las mejores ofertas en hoteles Irotama. Reserva tu estancia en Santa Marta con descuentos exclusivos y vive una experiencia frente al Caribe.","breadcrumb":{"@id":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/hoteles-irotama\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/hoteles-irotama\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/hoteles-irotama\/#primaryimage","url":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/wp-content\/uploads\/2026\/07\/PH-Irotama-1920x470-2.jpg","contentUrl":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/wp-content\/uploads\/2026\/07\/PH-Irotama-1920x470-2.jpg","width":1920,"height":470},{"@type":"BreadcrumbList","@id":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/hoteles-irotama\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/"},{"@type":"ListItem","position":2,"name":"Hoteles Irotama"}]},{"@type":"WebSite","@id":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/#website","url":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/","name":"Tiquetes Baratos","description":"M\u00e9xico, por ti viajar\u00e9","publisher":{"@id":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/#organization","name":"PriceTravel.com","url":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/#\/schema\/logo\/image\/","url":"https:\/\/3.12.161.119\/wp-content\/uploads\/2022\/08\/pricetravel.png","contentUrl":"https:\/\/3.12.161.119\/wp-content\/uploads\/2022\/08\/pricetravel.png","width":422,"height":56,"caption":"PriceTravel.com"},"image":{"@id":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PriceTravel","https:\/\/x.com\/PriceTravel","https:\/\/www.instagram.com\/pricetravel\/"]}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/wp-json\/wp\/v2\/dynamic-landing\/62873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/wp-json\/wp\/v2\/dynamic-landing"}],"about":[{"href":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/wp-json\/wp\/v2\/types\/dynamic-landing"}],"version-history":[{"count":2,"href":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/wp-json\/wp\/v2\/dynamic-landing\/62873\/revisions"}],"predecessor-version":[{"id":62889,"href":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/wp-json\/wp\/v2\/dynamic-landing\/62873\/revisions\/62889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/wp-json\/wp\/v2\/media\/62887"}],"wp:attachment":[{"href":"https:\/\/www.tiquetesbaratos.com\/es\/ofertas-de-viajes\/wp-json\/wp\/v2\/media?parent=62873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}